{"id":138,"date":"2021-01-28T11:27:50","date_gmt":"2021-01-28T11:27:50","guid":{"rendered":"http:\/\/www.bbc.com\/mundo\/noticias-internacional-55804567"},"modified":"2021-01-28T11:27:50","modified_gmt":"2021-01-28T11:27:50","slug":"vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas","status":"publish","type":"post","link":"http:\/\/cordobadirecto.com\/index.php\/2021\/01\/28\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas\/","title":{"rendered":"Vacunas contra el coronavirus: a qu\u00e9 se debe el secretismo que rodea los contratos entre los gobiernos y las farmac\u00e9uticas"},"content":{"rendered":"<div dir=\"ltr\" class=\"e1j2237y2 css-vf19ca-GridComponent e57qer20\">\n<div class=\"css-s561j-Container e1c9i7u10\">\n<ul role=\"list\" class=\"css-g8atbx-Person e1c9i7u12\">\n<li role=\"listitem\" class=\"css-dvly96-Name e1c9i7u13\">Guillermo D. Olmo @BBCgolmo<\/li>\n<li role=\"listitem\" class=\"css-1942rtw-Title e1c9i7u14\">BBC News Mundo<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p><time datetime=\"2021-01-28\" class=\"css-1gpsqpy-StyledTimestamp e4zesg50\">8 horas<\/time><\/p>\n<div dir=\"ltr\" class=\"css-1vcyzo4-GridComponent e57qer20\">\n<figure class=\"css-m91nxa-Figure e6bmn90\">\n<div dir=\"ltr\" class=\"css-18d1333-GridComponent e57qer20\">\n<div dir=\"ltr\" class=\"css-1p8eeyy-GridComponent e57qer20\" readability=\"6.5\">\n<div class=\"css-oijotl-ImagePlaceholder e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-5.jpg 240w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-6.jpg 320w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-7.jpg 480w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-8.jpg 624w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-9.jpg 800w\" alt=\"Vacuna de la covid.\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas.jpg\" width=\"976\" class=\"css-1vsigzm-StyledImg-fadeIn e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"css-19db9gm-Copyright etq3yw90\"><span class=\"css-ow3j0s-VisuallyHiddenText e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Getty Images<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"css-5z6hrn-GridComponent e57qer20\" readability=\"6\"><figcaption dir=\"ltr\" class=\"css-qu1vzc-Caption eede9f50\" readability=\"2\"><span class=\"css-ow3j0s-VisuallyHiddenText e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>La pandemia hace que la demanda mundial de vacunas sea superior a la oferta.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\"><b>El mundo entero se disputa una plaza para recibir la vacuna contra el coronavirus, un bien todav\u00eda demasiado escaso y producido por pocos laboratorios farmac\u00e9uticos. <\/b><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Los gobiernos firman contratos con las compa\u00f1\u00edas que han desarrollado esas vacunas en tiempo r\u00e9cord y, sin embargo, informaci\u00f3n cr\u00edtica de esos acuerdos permanece oculta para el gran p\u00fablico debido a estrictas cl\u00e1usulas de confidencialidad. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Cu\u00e1nto cuestan o c\u00f3mo se distribuir\u00e1n son detalles que en la mayor\u00eda de los casos la ciudadan\u00eda desconoce, porque as\u00ed lo exigen los acuerdos firmados.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">En Per\u00fa, por ejemplo, las negociaciones entre el gobierno y la compa\u00f1\u00eda Pfizer encallaron por este motivo. Y en Colombia el gobierno afirma que las cl\u00e1usulas de confidencialidad le impiden ofrecer a\u00fan un cron\u00f3grama claro de vacunaci\u00f3n.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">El problema es mundial.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"14\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">En respuesta a una petici\u00f3n de informaci\u00f3n en el Parlamento Europeo a mediados de noviembre, la comisaria de Salud, Estela Kiriakides, afirm\u00f3: &#8220;Debido a la naturaleza altamente competitiva de este mercado, la Comisi\u00f3n est\u00e1 legalmente imposibilitada para desvelar la informaci\u00f3n que contienen estos contratos&#8221;. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Y la ministra belga de Presupuesto, Eva de Bleeker, tuvo que retirar poco despu\u00e9s de publicarlo un mensaje en Twitter en el que recog\u00eda la lista de precios de los laboratorios con los que hab\u00eda negociado la UE. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">A las quejas por el incumplimiento de los compromisos adquiridos por algunos fabricantes de vacunas, se suman ahora las de las voces que exigen mayor transparencia en un asunto de salud p\u00fablica vital. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Y la pol\u00e9mica sigue subiendo de tono, sobre todo en la Uni\u00f3n Europea (UE), enojada despu\u00e9s de que los laboratorios Pfizer y AstraZeneca le comunicaran que no estar\u00e1n en condiciones de suministrar al bloque la cantidad de dosis iniciales acordadas.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Ello ha llevado a que, seg\u00fan fuentes de la UE citadas por la agencia Reuters, desde Bruselas se les exija a las farmac\u00e9uticas que hagan p\u00fablicos los t\u00e9rminos de los contratos y amenace con controlar las exportaciones de las vacunas producidas en Europa.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"7\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">\u00bfPor qu\u00e9 tanto secreto?<\/p>\n<\/div>\n<p><h2 id=\"Una-pr\u00e1ctica-habitual\" tabindex=\"-1\" class=\"css-4qzrek-SubHeading e14hemmw1\">Una pr\u00e1ctica habitual<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Seg\u00fan Jonathan Garc\u00eda, experto en salud p\u00fablica en la Universidad de Harvard, en EE.UU., &#8220;esto no es nada nuevo; es frecuente que en los contratos entre los sistemas de salud de los pa\u00edses y las farmac\u00e9uticas se incluyan cl\u00e1usulas de confidencialidad&#8221;. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">&#8220;Los laboratorios buscan fraccionar el mercado para poder negociar precios distintos con los distintos pa\u00edses&#8221;, a\u00f1ade. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Esto les permite negociar con los pa\u00edses en funci\u00f3n de sus recursos, ofreci\u00e9ndoles precios m\u00e1s bajos a los pa\u00edses pobres o en desarrollo y exigiendo cantidades m\u00e1s altas a los m\u00e1s ricos. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">La compa\u00f1\u00eda AstraZeneca ha revelado que la vacuna que ha desarrollado en colaboraci\u00f3n con la Universidad de Oxford tendr\u00e1 un coste aproximado de entre 3 y 4 d\u00f3lares por dosis (se requieren dos). Pero el suyo es por ahora un caso excepcional.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Adem\u00e1s de los precios, se mantienen muchas veces en secreto la informaci\u00f3n relativa a la producci\u00f3n y log\u00edstica, y las conocidas como cl\u00e1usulas de responsabilidad. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">En ellas se estipulan l\u00edmites a la responsabilidad de los laboratorios en el caso de posibles efectos adversos de los medicamentos y se indica que si hay diferencias no las resolver\u00e1n los tribunales nacionales, sino unas cortes especiales de arbitraje internacional. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-1vcyzo4-GridComponent e57qer20\">\n<figure class=\"css-m91nxa-Figure e6bmn90\">\n<div dir=\"ltr\" class=\"css-18d1333-GridComponent e57qer20\">\n<div dir=\"ltr\" class=\"css-1p8eeyy-GridComponent e57qer20\" readability=\"6.5\">\n<div class=\"css-oijotl-ImagePlaceholder e1whu0\" readability=\"8\"><noscript><img srcset=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-10.jpg 240w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-11.jpg 320w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-12.jpg 480w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-13.jpg 624w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-14.jpg 800w\" alt=\"Vacuna de Pfizer.\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-1.jpg\" width=\"976\" class=\"css-1vsigzm-StyledImg-fadeIn e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"css-19db9gm-Copyright etq3yw90\"><span class=\"css-ow3j0s-VisuallyHiddenText e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">Reuters<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"css-5z6hrn-GridComponent e57qer20\" readability=\"6\"><figcaption dir=\"ltr\" class=\"css-qu1vzc-Caption eede9f50\" readability=\"2\"><span class=\"css-ow3j0s-VisuallyHiddenText e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>Pfizer es una de las compa\u00f1\u00edas se\u00f1aladas por la exigencia de confidencialidad en los contratos.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Las voces que reclaman mayor transparencia alertan de que la urgencia por el desarrollo de una vacuna para una enfermedad que se ha cobrado ya m\u00e1s de dos millones de vidas en todo el mundo ha podido llevar a los gobiernos a aceptar limitaciones de responsabilidad a\u00fan mayores. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"11\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">En la Estrategia para la Adquisici\u00f3n de Vacunas que hizo p\u00fablica la Comisi\u00f3n Europea se dec\u00eda que &#8220;la responsabilidad por el desarrollo y el uso de la vacuna, incluida cualquier indemnizaci\u00f3n espec\u00edfica requerida, recaer\u00e1 sobre los Estados miembros que la adquieran&#8221;. <\/p>\n<\/div>\n<p><h2 id=\"El-caso-de-Per\u00fa\" tabindex=\"-1\" class=\"css-4qzrek-SubHeading e14hemmw1\">El caso de Per\u00fa<\/h2>\n<\/p>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Un pa\u00eds de Am\u00e9rica Latina, Per\u00fa, se ha convertido en ejemplo destacado de los problemas que acarrea esta limitaci\u00f3n de responsabilidad para las farmac\u00e9uticas. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Las negociaciones del gobierno peruano con la compa\u00f1\u00eda Pfizer para la adquisici\u00f3n de la vacuna no cuajaron porque, seg\u00fan dijo la ministra de Salud, Pilar Mazzetti, &#8220;se identificaron algunas cl\u00e1usulas que requer\u00edan un an\u00e1lisis m\u00e1s profundo para determinar la compatibilidad con las leyes peruanas y los alcances que puede asumir el Estado&#8221;. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">BBC Mundo trat\u00f3 de contactar con Pfizer, pero no obtuvo respuesta. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">La falta de acuerdo con Pfizer llev\u00f3 a las autoridades peruanas a buscar otras opciones, como la vacuna del fabricante chino Sinopharm. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-1vcyzo4-GridComponent e57qer20\">\n<figure class=\"css-m91nxa-Figure e6bmn90\">\n<div dir=\"ltr\" class=\"css-18d1333-GridComponent e57qer20\">\n<div dir=\"ltr\" class=\"css-1p8eeyy-GridComponent e57qer20\">\n<div class=\"css-oijotl-ImagePlaceholder e1whu0\"><noscript><img srcset=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-15.jpg 240w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-16.jpg 320w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-17.jpg 480w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-18.jpg 624w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-19.jpg 800w\" alt=\"Mujer recibe la vacuna en Hungr\u00eda.\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-2.jpg\" width=\"976\" class=\"css-1vsigzm-StyledImg-fadeIn e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"css-19db9gm-Copyright etq3yw90\"><span class=\"css-ow3j0s-VisuallyHiddenText e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">EPA<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"css-5z6hrn-GridComponent e57qer20\" readability=\"6\"><figcaption dir=\"ltr\" class=\"css-qu1vzc-Caption eede9f50\" readability=\"2\"><span class=\"css-ow3j0s-VisuallyHiddenText e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>El ritmo al que avanza la vacunaci\u00f3n var\u00eda seg\u00fan los pa\u00edses.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Al contrario de lo que sucede en otros pa\u00edses de la regi\u00f3n, como Argentina o Chile, la vacunaci\u00f3n no ha comenzado a\u00fan en Per\u00fa y las autoridades no han podido ofrecer un cronograma seguro. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">En Colombia, el gobierno ha sido objeto de fuertes cr\u00edticas por no haber comenzado a\u00fan a vacunar a la gente y haber aludido a las cl\u00e1usulas de confidencialidad para justificar por qu\u00e9 no pod\u00eda ofrecer a\u00fan una fecha para comenzar a hacerlo. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"15\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">La confidencialidad en los contratos, sin embargo, cuenta con defensores, con base, sobre todo, en los llamados &#8220;subsidios cruzados&#8221;. Al poder cobrarles m\u00e1s a los pa\u00edses ricos, los laboratorios se ven en condiciones de ofrecer precios asequibles a los pa\u00edses con menos recursos. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">El economista David Bardey se\u00f1ala en conversaci\u00f3n con BBC Mundo que si hubiera transparencia en los precios de los medicamentos, &#8220;ser\u00eda m\u00e1s complicado para los laboratorios cobrar precios m\u00e1s altos a los pa\u00edses m\u00e1s ricos si estos pueden observar precios menores para otros pa\u00edses&#8221;. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">&#8220;Si queremos que los pa\u00edses m\u00e1s desarrollados paguen m\u00e1s, es mejor que los precios no sean p\u00fablicos&#8221;, indica el experto, que alerta adem\u00e1s de que los pa\u00edses m\u00e1s avanzados est\u00e1n adquiriendo muchas m\u00e1s dosis de las que necesitan porque &#8220;sus gobiernos tienen una gran presi\u00f3n de su opini\u00f3n p\u00fablica y eso los est\u00e1 empujando a una especie de nacionalismo sanitario&#8221;. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Se suele aludir tambi\u00e9n al derecho que tienen las compa\u00f1\u00edas a obtener un beneficio de las grandes inversiones que hacen en investigaci\u00f3n. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Y un tercer factor son los derechos de propiedad intelectual. Un experto espa\u00f1ol en salud p\u00fablica que prefiri\u00f3 no dar su nombre resume el papel que, a su juicio, est\u00e1n jugando los grandes laboratorios occidentales: &#8220;Est\u00e1n defendiendo su patente para evitar que otros la fabriquen en la India y se las vendan a menor coste a los pa\u00edses pobres&#8221;. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-1vcyzo4-GridComponent e57qer20\">\n<figure class=\"css-m91nxa-Figure e6bmn90\">\n<div dir=\"ltr\" class=\"css-18d1333-GridComponent e57qer20\">\n<div dir=\"ltr\" class=\"css-1p8eeyy-GridComponent e57qer20\">\n<div class=\"css-oijotl-ImagePlaceholder e1whu0\"><noscript><img srcset=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-20.jpg 240w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-21.jpg 320w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-22.jpg 480w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-23.jpg 624w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-24.jpg 800w\" alt=\"Ursula Von Der Leyen, presidenta de la Comisi\u00f3n Europea.\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-3.jpg\" width=\"976\" class=\"css-1vsigzm-StyledImg-fadeIn e1enwo3v0\"><\/noscript><\/p>\n<p role=\"text\" class=\"css-19db9gm-Copyright etq3yw90\"><span class=\"css-ow3j0s-VisuallyHiddenText e1yt7oin0\">Fuente de la imagen, <\/span><span lang=\"en-GB\">EPA<\/span><\/p>\n<\/div>\n<\/div>\n<div dir=\"ltr\" class=\"css-5z6hrn-GridComponent e57qer20\" readability=\"7.5\"><figcaption dir=\"ltr\" class=\"css-qu1vzc-Caption eede9f50\" readability=\"5\"><span class=\"css-ow3j0s-VisuallyHiddenText e1yt7oin0\">Pie de foto, <\/span><\/p>\n<p>Ursula Von Der Leyen, presidenta de la Comisi\u00f3n Europea, se enfrenta al problema de hacer que las farmac\u00e9uticas cumplan sus compromisos.<\/p>\n<\/figcaption><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Jonathan Garc\u00eda cree que los argumentos a favor de la transparencia ganan valor en el contexto de la pandemia. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">&#8220;Estamos hablando de una emergencia sanitaria global, de algo que sucede cada 100 a\u00f1os, ante lo que uno esperar\u00eda que el sistema utilizara mecanismos mucho m\u00e1s transparentes y buscara un esquema m\u00e1s cooperativo. En cambio vemos que se sigue buscando un mercado monop\u00f3lico y mantener ventajas en los precios&#8221;. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"13\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Las diferencias en el acceso a las vacunas han llevado al mundo a un riesgo de &#8220;fracaso moral catastr\u00f3fico&#8221;, como defini\u00f3 el director de la Organizaci\u00f3n Mundial de la Salud, el doctor Tedros Adhanom Ghebreyesus, el hecho de que los pa\u00edses m\u00e1s necesitados vayan a tener que esperar a\u00f1os para inmunizar a su poblaci\u00f3n. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"9\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">La historia de las epidemias muestra que no ser\u00eda la primera vez. Ya sucedi\u00f3 con la poliomielitis y la viruela, enfermedades erradicadas mucho antes en los pa\u00edses m\u00e1s avanzados. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"10\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">O con el VIH, que todav\u00eda diezma a muchas poblaciones africanas cuando los pacientes en el llamado primer mundo han visto prolongada significativamente su esperanza de vida gracias al desarrollo de los tratamientos antirretrovirales. <\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">&#8220;Los medicamentos est\u00e1n disponibles; el problema son los costos&#8221;, indica Garc\u00eda.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"12\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\">Y los pa\u00edses de renta media, como la mayor\u00eda de los de Am\u00e9rica Latina, no pueden permitirse al negociar con los laboratorios la actitud exigente mostrada por la Uni\u00f3n Europea, un bloque formado por 27 estados entre los m\u00e1s pr\u00f3speros del mundo.<\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"7\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\"><i class=\"css-h1y5j7 ewc4zcb0\">*Con informaci\u00f3n adicional de Mart\u00edn Riepl en Lima y Carlos Serrano en Miami. <\/i><\/p>\n<\/div>\n<div dir=\"ltr\" class=\"css-1vcyzo4-GridComponent e57qer20\">\n<figure class=\"css-m91nxa-Figure e6bmn90\">\n<div dir=\"ltr\" class=\"css-18d1333-GridComponent e57qer20\">\n<div dir=\"ltr\" class=\"css-1p8eeyy-GridComponent e57qer20\">\n<div class=\"css-3p1z99-ImagePlaceholder e1whu0\"><noscript><img srcset=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-25.jpg 240w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-26.jpg 320w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-27.jpg 464w\" alt=\"L\u00ednea\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/vacunas-contra-el-coronavirus-a-que-se-debe-el-secretismo-que-rodea-los-contratos-entre-los-gobiernos-y-las-farmaceuticas-4.jpg\" width=\"464\" class=\"css-1vsigzm-StyledImg-fadeIn e1enwo3v0\"><\/noscript><\/div>\n<\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div dir=\"ltr\" class=\"css-oywjep-GridComponent e57qer20\" readability=\"8\">\n<p dir=\"ltr\" class=\"css-1ikvhrr-Paragraph e1cc2ql70\"><i class=\"css-h1y5j7 ewc4zcb0\">Ahora puedes recibir notificaciones de BBC News Mundo. Descarga nuestra app y act\u00edvalas para no perderte nuestro mejor contenido.<\/i><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Guillermo D. Olmo @BBCgolmo BBC News Mundo 8 horas Fuente de la imagen, Getty Images Pie de foto, La pandemia hace que la demanda mundial de vacunas sea superior a la oferta. El mundo entero se disputa una plaza para recibir la vacuna contra el coronavirus, un bien todav\u00eda demasiado escaso y producido por pocos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[24],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/138"}],"collection":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/comments?post=138"}],"version-history":[{"count":0,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media\/140"}],"wp:attachment":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media?parent=138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/categories?post=138"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/tags?post=138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}