{"id":152383,"date":"2024-07-07T07:56:03","date_gmt":"2024-07-07T07:56:03","guid":{"rendered":"https:\/\/www.ole.com.ar\/futbol-ascenso\/ascenso_0_06cBHfxVIR.html"},"modified":"2024-07-07T07:56:03","modified_gmt":"2024-07-07T07:56:03","slug":"almagro-temperley-y-brown-talleres-no-pasaron-del-cero","status":"publish","type":"post","link":"http:\/\/cordobadirecto.com\/index.php\/2024\/07\/07\/almagro-temperley-y-brown-talleres-no-pasaron-del-cero\/","title":{"rendered":"Almagro-Temperley y Brown-Talleres, no pasaron del cero"},"content":{"rendered":"<p><time class=\"createDate\" datetime=\"2024-07-06T19:28:17-03:00\">06\/07\/2024 22:28hs.<\/time><\/p>\n<div id=\"storyBody\">\n<div class=\"custom-text \" readability=\"32.300751879699\">\n<p>Todos estaban necesitando una victorias. Todos buscaban acercarse a los objetivos que tiene por delante. Sin embargo, ninguno tuvo la lucidez necesaria para romper el cero y quedarse con tres puntos fundamentales para el campeonato. <strong>Es que <a href=\"https:\/\/www.ole.com.ar\/tema\/almagro.html\" title=\"Almagro\" alt=\"Almagro\" class=\"slug\">Almagro<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/temperley.html\" title=\"temperley\" alt=\"temperley\" class=\"slug\">Temperley <\/a>igualaron en Jos\u00e9 Ingenieros y <a href=\"https:\/\/www.ole.com.ar\/tema\/brown-de-adrogue.html\" title=\"Brown de Adrogu\u00e9\" alt=\"Brown de Adrogu\u00e9\" class=\"slug\">Brown de Adrogu\u00e9<\/a> y <a href=\"https:\/\/www.ole.com.ar\/tema\/talleres-re.html\" title=\"Talleres (RE)\" alt=\"Talleres (RE)\" class=\"slug\">Talleres <\/a>de Remedios de Escalada hicieron lo propio en el Sur del conurbano bonaerense.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"37\">\n<p>Por un lado, el Tricolor buscaba vencer en su casa para escaparse del fondo. Y si bien cont\u00f3 con las mejores chances, no las aprovech\u00f3 e igual\u00f3 con un Gasolero que permanece en puestos de Reducido pero que no logr\u00f3 aproximarse a la cima de la Zona B. <strong>La igualdad termin\u00f3 siendo el resultado m\u00e1s justo para dos equipos que mostraron sus limitaciones.<\/strong><\/p>\n<\/div>\n<div class=\"custom-text \" readability=\"39.049676025918\">\n<p>Por el otro,<strong> el Trico y el Rojo jugaron duelo clave en el Interzonal de la fecha. <\/strong>Brown, \u00faltimo en su grupo y cada vez m\u00e1s complicado con la permanencia en la categor\u00eda (acumula apenas una victoria en la temporada y lleva diez sin ganar), evidenci\u00f3 las fallas que lo llevaron a este presente ya sin el hist\u00f3rico <a href=\"https:\/\/www.ole.com.ar\/tema\/pablo-vico.html\" title=\"Pablo Vic\u00f3\" alt=\"Pablo Vic\u00f3\" class=\"slug\">Pablo Vic\u00f3<\/a> en el banco de suplentes. Mientras que <strong>Talleres<\/strong>, que tom\u00f3 un poco de aire en la pelea de abajo, <strong>no supo aprovechas sus oportunidades.<\/strong><\/p>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6.5\">\n<section readability=\"3\"><picture><img alt=\"Liga Profesional: los nueve amistosos del s\u00e1bado, formaciones y goleadores\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2024\/07\/almagro-temperley-y-brown-talleres-no-pasaron-del-cero.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Liga Profesional: los nueve amistosos del s\u00e1bado, formaciones y goleadores<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"El Deportivo Madryn de Graci\u00e1n sigue intratable\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2024\/07\/almagro-temperley-y-brown-talleres-no-pasaron-del-cero-1.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>El Deportivo Madryn de Graci\u00e1n sigue intratable<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Atlanta rescat\u00f3 un punto ag\u00f3nico\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2024\/07\/almagro-temperley-y-brown-talleres-no-pasaron-del-cero-2.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Atlanta rescat\u00f3 un punto ag\u00f3nico<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Francia fue demasiado para Los Pumas en el debut de Felipe Contepomi\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2024\/07\/almagro-temperley-y-brown-talleres-no-pasaron-del-cero-3.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Francia fue demasiado para Los Pumas en el debut de Felipe Contepomi<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<div class=\"sc-a7166897-0 exHLBh\" readability=\"6\">\n<section readability=\"2\"><picture><img alt=\"Mundial U17: Argentina le gan\u00f3 a Egipto y jugar\u00e1 por el 9\u00b0 lugar\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2024\/07\/almagro-temperley-y-brown-talleres-no-pasaron-del-cero-4.jpg\" width=\"290\" height=\"290\" decoding=\"async\" data-nimg=\"future\" loading=\"lazy\"><\/picture>\n<p><span>Mir\u00e1 tambi\u00e9n<\/span><\/p>\n<hr>\n<h3>Mundial U17: Argentina le gan\u00f3 a Egipto y jugar\u00e1 por el 9\u00b0 lugar<\/h3>\n<\/p>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>06\/07\/2024 22:28hs. Todos estaban necesitando una victorias. Todos buscaban acercarse a los objetivos que tiene por delante. Sin embargo, ninguno tuvo la lucidez necesaria para romper el cero y quedarse con tres puntos fundamentales para el campeonato. Es que Almagro y Temperley igualaron en Jos\u00e9 Ingenieros y Brown de Adrogu\u00e9 y Talleres de Remedios de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":152384,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/152383"}],"collection":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/comments?post=152383"}],"version-history":[{"count":0,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/152383\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media\/152384"}],"wp:attachment":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media?parent=152383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/categories?post=152383"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/tags?post=152383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}