{"id":206413,"date":"2026-09-02T12:50:53","date_gmt":"2026-09-02T12:50:53","guid":{"rendered":"https:\/\/cordoba.gob.ar\/?p=93757"},"modified":"2026-09-02T12:50:53","modified_gmt":"2026-09-02T12:50:53","slug":"relevan-el-estado-de-los-desagues-y-canales-de-la-ciudad-para-evitar-anegamientos-en-la-temporada-de-lluvias","status":"publish","type":"post","link":"http:\/\/cordobadirecto.com\/index.php\/2026\/09\/02\/relevan-el-estado-de-los-desagues-y-canales-de-la-ciudad-para-evitar-anegamientos-en-la-temporada-de-lluvias\/","title":{"rendered":"Relevan el estado de los desag\u00fces y canales de la ciudad para evitar anegamientos en la temporada de lluvias"},"content":{"rendered":"<div><img src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2026\/09\/relevan-el-estado-de-los-desagues-y-canales-de-la-ciudad-para-evitar-anegamientos-en-la-temporada-de-lluvias.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<hr>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Previo a la \u00e9poca de lluvias, la Municipalidad de C\u00f3rdoba intensifica el relevamiento habitual sobre las condiciones de los desag\u00fces, canales, alcantarillas y bocas de tormenta, especialmente en las zonas anegables de la ciudad.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">El objetivo es identificar posibles obstrucciones, deterioros o acumulaci\u00f3n de residuos que puedan afectar el normal escurrimiento del agua en el sistema de drenaje.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Posteriormente, cada informe del personal de Defensa Civil es derivado al \u00e1rea encargada del arreglo de la situaci\u00f3n identificada. Por parte del municipio actuar\u00e1n el Ente C\u00f3rdoba Obras y Servicios (COyS), la Direcci\u00f3n de Higiene Urbana y los Centros Operativos de cada CPC.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Si fuera necesario intervenir en canales u otras instalaciones, las tareas se coordinar\u00e1n con la Administraci\u00f3n Provincial de Recursos H\u00eddricos (APRHI).<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Estas acciones se complementan con el trabajo que el Ente C\u00f3rdoba Obras y Servicios (COyS) realiza durante todo el a\u00f1o para la limpieza y desobstrucci\u00f3n de bocas de tormenta en distintos puntos de la ciudad.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">El relevamiento comenz\u00f3 en el sector norte, incluyendo los barrios Arg\u00fcello Norte, Villa 9 de Julio, Remo Copello, Villa Serrana, y continuar\u00e1 en Villa P\u00e1ez, entre otros sectores de la ciudad.<\/p>\n<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\">Los trabajos forman parte del mantenimiento preventivo de la infraestructura pluvial de la ciudad, operando con anticipaci\u00f3n a la temporada de lluvias, este a\u00f1o acentuada por el fen\u00f3meno clim\u00e1tico de \u201cEl Ni\u00f1o\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previo a la \u00e9poca de lluvias, la Municipalidad de C\u00f3rdoba intensifica el relevamiento habitual sobre las condiciones de los desag\u00fces, canales, alcantarillas y bocas de tormenta, especialmente en las zonas anegables de la ciudad. El objetivo es identificar posibles obstrucciones, deterioros o acumulaci\u00f3n de residuos que puedan afectar el normal escurrimiento del agua en el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":206414,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[44],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/206413"}],"collection":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/comments?post=206413"}],"version-history":[{"count":0,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/206413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media\/206414"}],"wp:attachment":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media?parent=206413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/categories?post=206413"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/tags?post=206413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}