{"id":268,"date":"2021-01-29T08:00:43","date_gmt":"2021-01-29T08:00:43","guid":{"rendered":"https:\/\/www.redeszone.net\/?post_type=noticias&amp;p=370492"},"modified":"2021-01-29T08:00:43","modified_gmt":"2021-01-29T08:00:43","slug":"paginas-phishing-en-tiempo-real-la-ultima-amenaza-para-robar-contrasenas","status":"publish","type":"post","link":"http:\/\/cordobadirecto.com\/index.php\/2021\/01\/29\/paginas-phishing-en-tiempo-real-la-ultima-amenaza-para-robar-contrasenas\/","title":{"rendered":"P\u00e1ginas Phishing en tiempo real, la \u00faltima amenaza para robar contrase\u00f1as"},"content":{"rendered":"<h2>Phishing en tiempo real, el \u00faltimo m\u00e9todo para atacar<\/h2>\n<p>Se trata de una nueva herramienta de <strong>LogoKit<\/strong>. Es un kit de ataques Phishing que se ha detectado ya cientos de dominios \u00fanicos en las \u00faltimas semanas. Ha sido desarrollado por un grupo de piratas inform\u00e1ticos y lo que hace es cambiar los logos y el texto de una p\u00e1gina Phishing en tiempo real para adaptarse a la v\u00edctima.<\/p>\n<p>Como hemos mencionado, este tipo de ataques se ha perfeccionado con el paso del tiempo. Se adaptan cada vez m\u00e1s a las v\u00edctimas para lograr su objetivo y poder saltarse las medidas de seguridad. Seg\u00fan indica la empresa de seguridad inform\u00e1tica <strong>RiskIQ<\/strong>, que ha estado siguiendo su evoluci\u00f3n, este kit ya se est\u00e1 explotando de manera continua.<\/p>\n<p>Concretamente, esta empresa de seguridad cibern\u00e9tica ha detectado 300 sitios \u00fanicos en la \u00faltima semana y m\u00e1s de 700 en el \u00faltimo mes. Indican que LogoKit se basa en enviar a los usuarios enlaces de Phishing que contienen sus direcciones de correo electr\u00f3nico.<\/p>\n<p><img src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/paginas-phishing-en-tiempo-real-la-ultima-amenaza-para-robar-contrasenas.jpg\" loading=\"lazy\" class=\"aligncenter size-full wp-image-314548\" alt=\"Tiempo de ataques Phishing\" width=\"1200\" height=\"664\"><\/p>\n<h3>LogoKit se adapta a cada empresa<\/h3>\n<p>Una vez que una v\u00edctima navega a la URL, LogoKit obtiene el <strong>logotipo de la empresa<\/strong> de un servicio de terceros, como Clearbit o la base de datos favicon de Google. Si una v\u00edctima ingresa su contrase\u00f1a, LogoKit realiza una solicitud y env\u00eda el e-mail y la clave de la v\u00edctima a una fuente externa y posteriormente redirige al usuario al sitio web leg\u00edtimo.<\/p>\n<p>Para conseguir esto, seg\u00fan indican los investigadores de seguridad, LogoKit utiliza un conjunto de<strong> funciones JavaScript integrables<\/strong>, que se pueden agregar a cualquier formulario de inicio de sesi\u00f3n gen\u00e9rico.<\/p>\n<p>Hay que tener en cuenta que esto es diferente de los <strong>kits de Phishing est\u00e1ndares<\/strong>, la mayor\u00eda de los cuales necesitan plantillas de p\u00edxeles perfectos que imitan las p\u00e1ginas de autenticaci\u00f3n de una empresa. La modularidad de este kit novedoso permite a un atacante apuntar a cualquier empresa que quieran simplemente con personalizarlo y realizar un montaje en poco tiempo. Pueden crear cientos de ataques diferentes en una semana.<\/p>\n<p>Desde RiskIQ indican que han visto c\u00f3mo LogoKit ha sido utilizado para <strong>imitar y crear p\u00e1ginas de inicio de sesi\u00f3n<\/strong> en servicios muy diversos, entre los que podemos mencionar OneDrive y Office 365.<\/p>\n<p>Tambi\u00e9n hay que indicar que este kit es muy peque\u00f1o, por lo que puede ser alojado en sitios pirateados y p\u00e1ginas leg\u00edtimas de empresas de todo tipo donde quiere dirigirse. Adem\u00e1s, al ser una colecci\u00f3n de archivos JavaScript, los recursos pueden ser alojados en servicios p\u00fablicos de confianza, como puede ser GitHub y otros similares.<\/p>\n<p>Una vez m\u00e1s, debemos estar protegidos adecuadamente contra este tipo de amenazas en la red. Os dejamos un tutorial donde explicamos <a href=\"https:\/\/www.redeszone.net\/tutoriales\/seguridad\/riesgos-phishing-como-funciona-detectarlo\/\">c\u00f3mo funciona el Phishing<\/a>. All\u00ed damos algunos consejos importantes para evitar ser v\u00edctimas de este problema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Phishing en tiempo real, el \u00faltimo m\u00e9todo para atacar Se trata de una nueva herramienta de LogoKit. Es un kit de ataques Phishing que se ha detectado ya cientos de dominios \u00fanicos en las \u00faltimas semanas. Ha sido desarrollado por un grupo de piratas inform\u00e1ticos y lo que hace es cambiar los logos y el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":269,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[42],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/268"}],"collection":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/comments?post=268"}],"version-history":[{"count":0,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/268\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media\/269"}],"wp:attachment":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media?parent=268"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/categories?post=268"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/tags?post=268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}