{"id":3752,"date":"2021-03-26T12:52:02","date_gmt":"2021-03-26T12:52:02","guid":{"rendered":"https:\/\/enelmedio.tv\/?p=3947"},"modified":"2021-03-26T12:52:02","modified_gmt":"2021-03-26T12:52:02","slug":"a-30-anos-de-la-creacion-del-mercosur-fernandez-llamo-a-sus-pares-a-profundizar-la-integracion","status":"publish","type":"post","link":"http:\/\/cordobadirecto.com\/index.php\/2021\/03\/26\/a-30-anos-de-la-creacion-del-mercosur-fernandez-llamo-a-sus-pares-a-profundizar-la-integracion\/","title":{"rendered":"A 30 a\u00f1os de la creaci\u00f3n del Mercosur, Fern\u00e1ndez llam\u00f3 a sus pares a \u201cprofundizar la integraci\u00f3n\u201d"},"content":{"rendered":"<div><img src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/03\/a-30-anos-de-la-creacion-del-mercosur-fernandez-llamo-a-sus-pares-a-profundizar-la-integracion.jpg\" class=\"ff-og-image-inserted\"><\/div>\n<p>El presidente Alberto Fern\u00e1ndez llam\u00f3 hoy a sus pares del Mercosur a \u201credoblar esfuerzos y profundizar la voluntad de caminar juntos\u201d,&nbsp;<strong>al cumplirse 30 a\u00f1os de la creaci\u00f3n del bloque<\/strong>, y pidi\u00f3 \u201cno erosionar las estructuras productivas\u201d de los pa\u00edses miembro.<\/p>\n<p>\u201cNuestros pueblos lo merecen; vamos por muchos a\u00f1os m\u00e1s de Mercosur. No es tiempo de individualidades, nadie se salva solo, como dice el Papa Francisco\u201d, dijo el mandatario al abrir desde el Museo del Bicentenario el encuentro, que se realiza en forma virtual por las restricciones impuestas por la pandemia de coronavirus y la llegada de la segunda ola a la regi\u00f3n.<\/p>\n<p>En ese marco, Fern\u00e1ndez dijo que&nbsp;<a href=\"https:\/\/www.telam.com.ar\/notas\/202103\/548716-rebaja-arancel-externo-comun-mercosur-alberto-fernandez.html\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>la Argentina llevar\u00e1 a la reuni\u00f3n de cancilleres del Mercosur del pr\u00f3ximo 22 de abril la propuesta de que el arancel externo com\u00fan \u201cse base en preservar el equilibrio entre los sectores agroindustriales e industriales, y corregir las inconsistencias\u201d.<\/strong><\/a><\/p>\n<p>Adem\u00e1s, destac\u00f3 el crecimiento del comercio en el Mercosur \u201ctanto en volumen, como en calidad y valor agregado\u201d, y remarc\u00f3 que&nbsp;<strong>\u201cno es un bloque cerrado de comercio exterior sino una plataforma para que nuestros pa\u00edses se proyecten al resto del mundo\u201d<\/strong>.<\/p>\n<blockquote readability=\"6\">\n<p>\u201cEl Mercosur dej\u00f3 atr\u00e1s la l\u00f3gica de la rivalidad para pasar a la l\u00f3gica de la cooperaci\u00f3n\u201d<\/p>\n<\/blockquote>\n<p><strong>\u201cLa inserci\u00f3n del Mercosur en el mundo global debe darse en favor de nuestros sectores productivos y no en su contra\u201d<\/strong>,asever\u00f3 el presidente argentino.<\/p>\n<p>Finalmente, sostuvo que la conformaci\u00f3n del Mercosur hace 30 a\u00f1os&nbsp;<strong>\u201cdej\u00f3 atr\u00e1s la l\u00f3gica de la rivalidad para pasar a la l\u00f3gica de la cooperaci\u00f3n\u201d<\/strong>&nbsp;y sostuvo que el bloque \u201cfavoreci\u00f3 la consolidaci\u00f3n de las instituciones democr\u00e1ticas de la regi\u00f3n\u201d.<\/p>\n<p>\u201cSent\u00f3 las bases para dejar atr\u00e1s el peligro de las dictaduras y entramos a un proceso de integraci\u00f3n de importancia para construir confianza mutua\u201d, concluy\u00f3.<\/p>\n<p>Fuente: TELAM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Alberto Fern\u00e1ndez llam\u00f3 hoy a sus pares del Mercosur a \u201credoblar esfuerzos y profundizar la voluntad de caminar juntos\u201d,&nbsp;al cumplirse 30 a\u00f1os de la creaci\u00f3n del bloque, y pidi\u00f3 \u201cno erosionar las estructuras productivas\u201d de los pa\u00edses miembro. \u201cNuestros pueblos lo merecen; vamos por muchos a\u00f1os m\u00e1s de Mercosur. No es tiempo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/3752"}],"collection":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/comments?post=3752"}],"version-history":[{"count":0,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/3752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media\/3753"}],"wp:attachment":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media?parent=3752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/categories?post=3752"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/tags?post=3752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}