{"id":443,"date":"2021-01-28T09:47:00","date_gmt":"2021-01-28T09:47:00","guid":{"rendered":"https:\/\/lmdiario.com.ar\/contenido\/271497\/japon-ratifica-que-prepara-los-juegos-con-todos-los-escenarios-posibles"},"modified":"2021-01-28T09:47:00","modified_gmt":"2021-01-28T09:47:00","slug":"japon-ratifica-que-prepara-los-juegos-con-todos-los-escenarios-posibles","status":"publish","type":"post","link":"http:\/\/cordobadirecto.com\/index.php\/2021\/01\/28\/japon-ratifica-que-prepara-los-juegos-con-todos-los-escenarios-posibles\/","title":{"rendered":"Jap\u00f3n ratifica que prepara los Juegos con &#8220;todos los escenarios posibles&#8221;"},"content":{"rendered":"<div readability=\"34\"> <img alt=\"Tokio\" class=\"img-responsive\" height=\"667\" loading=\"lazy\" sizes=\"auto\" src=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/japon-ratifica-que-prepara-los-juegos-con-todos-los-escenarios-posibles.jpg\" srcset=\"http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/japon-ratifica-que-prepara-los-juegos-con-todos-los-escenarios-posibles.jpg 1000w, http:\/\/cordobadirecto.com\/wp-content\/uploads\/2021\/01\/japon-ratifica-que-prepara-los-juegos-con-todos-los-escenarios-posibles-1.jpg 400w\" width=\"1000\"> <\/p>\n<p> <span>&#8220;Estamos convencidos de que todas estas dudas se despejar\u00e1n el d\u00eda de la apertura&#8221;, indicaron los organizadores. <\/span> <span>Foto: gentileza<\/span> <\/p>\n<\/p><\/div>\n<div readability=\"83.628548256285\">\n<p><strong>Los organizadores de los Juegos Ol\u00edmpicos de Tokio 2020, programados desde el 23 de julio al 8 de agosto pr\u00f3ximos, ratificaron este jueves que se preparan para celebrar la cita ol\u00edmpica &#8220;con todos los escenarios posibles&#8221; <\/strong>ante la dif\u00edcil situaci\u00f3n sanitaria a nivel mundial que gener\u00f3 la pandemia de coronavirus.<\/p>\n<p>&#8220;Nos estamos preparando para todos los escenarios posibles&#8221; ratificaron los responsables del Comit\u00e9 organizador de los Juegos que fueron pospuestos el a\u00f1o pasado debido a la pandemia.<\/p>\n<p><strong>La determinaci\u00f3n de realizar la cita ol\u00edmpica &#8220;en cualquier situaci\u00f3n&#8221; incluye tambi\u00e9n las posibilidades &#8220;de que no haya vacunas efectivas&#8221; o &#8220;que no se pueda vacunar a un elevado n\u00famero de gente&#8221;<\/strong>, dijo en rueda de prensa el CEO de Tokio 2020, Toshiro Muto, seg\u00fan public\u00f3 este jueves el diario catal\u00e1n Mundo Deportivo.<\/p>\n<p>Los anfitriones quisieron despejar una vez m\u00e1s las dudas que se plantean sobre los Juegos debido a la situaci\u00f3n sanitaria tanto en Jap\u00f3n como en el resto del mundo, en una comparecencia ante los medios celebrada un d\u00eda despu\u00e9s de la Comisi\u00f3n Ejecutiva del COI, donde se lanz\u00f3 un mensaje similar.<\/p>\n<p><strong>&#8220;Estamos convencidos de que todas estas dudas se despejar\u00e1n el d\u00eda de la apertura de los Juegos&#8221;<\/strong>, afirm\u00f3 el presidente del comit\u00e9 organizador, Yoshiro Mori, despu\u00e9s de que el m\u00e1ximo responsable del COI, Thomas Bach, afirmara que ese organismo &#8220;no pierde tiempo en conjeturas&#8221; y que est\u00e1n centrados en la fecha de la ceremonia inaugural, el 23 de julio.<\/p>\n<p><strong>Los organizadores nipones recalcaron que barajan un amplio elenco de planes para diferentes posibilidades de evoluci\u00f3n de la pandemia<\/strong>, que afectar\u00e1n a las medidas de prevenci\u00f3n de contagios entre atletas y a la presencia de p\u00fablico en las gradas, asuntos que deber\u00e1n ser definidos en los pr\u00f3ximos meses.<\/p>\n<p>Una de las claves en este sentido ser\u00e1 la inoculaci\u00f3n de vacunas entre los atletas extranjeros, una medida sanitaria que el COI promover\u00e1 aunque no se espera que sea obligatoria, as\u00ed como la vacunaci\u00f3n a gran escala en Jap\u00f3n, un proceso que no comenzar\u00e1 sobre finales de febrero.<\/p>\n<p><strong>&#8220;Tenemos que ser muy pacientes con los preparativos para la vacuna&#8221;, a<\/strong>segur\u00f3 Muto, quien se\u00f1al\u00f3 que cada pa\u00eds &#8220;tiene sus propias medidas sanitarias&#8221; y a\u00f1adi\u00f3 que todav\u00eda es preciso &#8220;discutir sobre distintos futuros escenarios antes de llegar a conclusiones&#8221;.<\/p>\n<p><span>Fuente: T\u00e9lam&nbsp;<\/span><\/p>\n<p>Noticia relacionada:&nbsp;<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Estamos convencidos de que todas estas dudas se despejar\u00e1n el d\u00eda de la apertura&#8221;, indicaron los organizadores. Foto: gentileza Los organizadores de los Juegos Ol\u00edmpicos de Tokio 2020, programados desde el 23 de julio al 8 de agosto pr\u00f3ximos, ratificaron este jueves que se preparan para celebrar la cita ol\u00edmpica &#8220;con todos los escenarios posibles&#8221; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[21],"tags":[],"_links":{"self":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/443"}],"collection":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/comments?post=443"}],"version-history":[{"count":0,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/posts\/443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media\/444"}],"wp:attachment":[{"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/media?parent=443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/categories?post=443"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/cordobadirecto.com\/index.php\/wp-json\/wp\/v2\/tags?post=443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}